{"id":186095,"date":"2026-07-11T16:14:02","date_gmt":"2026-07-11T22:14:02","guid":{"rendered":"https:\/\/tecscience.tec.mx\/es\/?post_type=divulgacion-ciencia&#038;p=186095"},"modified":"2026-07-13T17:02:14","modified_gmt":"2026-07-13T23:02:14","slug":"voz-artificial-y-aprendizaje","status":"publish","type":"divulgacion-ciencia","link":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/","title":{"rendered":"\u00bfPuede una voz artificial ense\u00f1arnos a hablar con intenci\u00f3n?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Por<strong> Lidia Fabi\u00e1n&nbsp;Acevedo <\/strong>y<strong> Tania Mireles Amador<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En un sal\u00f3n de preparatoria, un grupo de estudiantes escucha su propia voz\u2026 pero no es exactamente la suya, es una versi\u00f3n generada con inteligencia artificial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al principio, lo que sorprende es lo real que suena, pero pronto ocurre algo m\u00e1s interesante: los estudiantes comienzan a notar matices que antes pasaban desapercibidos, como <strong>la entonaci\u00f3n, las pausas y la emoci\u00f3n<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por primera vez, no solo escuchan lo que dicen, sino c\u00f3mo lo dicen. Esa fue la base de una experiencia educativa que buscaba responder una pregunta sencilla, pero profundamente humana: \u00bfes posible ense\u00f1ar a hablar con intenci\u00f3n en la era digital?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En muchos contextos educativos, hablar se entiende como una habilidad espont\u00e1nea. Sin embargo, comunicar con intenci\u00f3n; es decir, <strong>transmitir ideas, emociones y prop\u00f3sitos<\/strong> de manera consciente, es un proceso completo que rara vez se ense\u00f1a de forma expl\u00edcita.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este escenario, la inteligencia artificial comenz\u00f3 a explorarse como un fin en s\u00ed mismo y como una herramienta para mediar en ese proceso.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s del uso de una plataforma de generaci\u00f3n de voz, un grupo de estudiantes de PrepaTec trabajaron en la creaci\u00f3n de guiones que posteriormente fueron transformados en audio con inteligencia artificial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ejercicio permiti\u00f3 que escucharan activamente versiones de su discurso y que pudieran identificar c\u00f3mo <strong>la entonaci\u00f3n, el ritmo y la carga emocional<\/strong> son relevantes para cualquier acto comunicativo y, a su vez, reconocieron que la voz de la IA, para sonar real, requiere de conocimientos b\u00e1sicos sobre la escritura, como puntuaci\u00f3n y gram\u00e1tica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo relevante no era que la voz sonara perfecta, sino que el audio funcionara como reflejo de la intenci\u00f3n comunicativa de s\u00ed mismos.&nbsp;El ejercicio provoc\u00f3 un cambio importante: los estudiantes dejaron de ver la comunicaci\u00f3n oral como algo autom\u00e1tico y comenzaron a analizarla. <strong>Escuchar su propio discurso<\/strong>, mediado por una voz artificial, les permiti\u00f3 identificar inconsistencias entre lo que quer\u00edan decir y lo que realmente transmit\u00edan.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entre lo humano y lo artificial&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio se llev\u00f3 a cabo con 147 estudiantes de nivel medio superior. Al comparar su desempe\u00f1o con el del grupo que no utiliz\u00f3 inteligencia artificial, se observaron diferencias relevantes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estudiantes que trabajaron con esta herramienta mostraron un aumento en la motivaci\u00f3n: la posibilidad de <strong>escuchar su voz transformada<\/strong> gener\u00f3 mayor inter\u00e9s y compromiso con la actividad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se registraron <strong>mejoras en el desempe\u00f1o acad\u00e9mico<\/strong>, con diferencias que alcanzaron hasta un 12.7% en algunos indicadores. Las evaluaciones reflejaron avances en la capacidad de estructurar mensajes, modular la voz y transmitir emociones de manera m\u00e1s clara.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, uno de los hallazgos m\u00e1s significativos fue cualitativo: los estudiantes comenzaron a reconocer la importancia de la intenci\u00f3n al momento de comunicarse.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Uno de los aspectos m\u00e1s interesantes de la experiencia fue <strong>la relaci\u00f3n entre voz y emoci\u00f3n<\/strong>. Al trabajar con audios, los estudiantes no solo se enfocaron en el contenido de sus mensajes, sino en la manera en que estos son percibidos.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto abri\u00f3 una reflexi\u00f3n clave: comunicar es transmitir informaci\u00f3n y generar efectos en quienes escuchan.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En algunos casos, los estudiantes identificaron que la inteligencia artificial lograba reproducir entonaciones b\u00e1sicas, pero ten\u00eda dificultades para <strong>expresar emociones complejas<\/strong> o matices m\u00e1s sutiles.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta limitaci\u00f3n fue un punto de partida para discutir qu\u00e9 hace que una voz no sea verdaderamente humana. As\u00ed, la tecnolog\u00eda ayud\u00f3 a delimitar la expresi\u00f3n humana.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La experiencia tambi\u00e9n plante\u00f3 preguntas \u00e9ticas y pedag\u00f3gicas: \u00bfhasta qu\u00e9 punto es v\u00e1lido utilizar la inteligencia artificial para producir mensajes? \u00bfCu\u00e1l es el papel del estudiante en un proceso mediado por la tecnolog\u00eda?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lejos de promover el uso autom\u00e1tico de la inteligencia artificial, el trabajo en el aula se centr\u00f3 en <strong>el uso consciente y reflexivo<\/strong>. Los estudiantes generaban audios y analizaban sus decisiones de escritura, cuestionaban los resultados y reconoc\u00edan los alcances y limitaciones de la IA.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este contexto, la inteligencia artificial se convirti\u00f3 en un espacio de di\u00e1logo, m\u00e1s que en una soluci\u00f3n.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escuchar(se) y sus beneficios<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En un entorno donde gran parte de la comunicaci\u00f3n ocurre a trav\u00e9s de pantallas, aprender a hablar con intenci\u00f3n se vuelve m\u00e1s relevante que nunca.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se trata solo de decir algo correctamente y de comprender el impacto de lo que se dice.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando los estudiantes comienzan a escucharse con atenci\u00f3n, algo cambia: reconocen sus emociones, ajustan su discurso y se vuelven m\u00e1s conscientes de su relaci\u00f3n con los otros. En ese proceso, la comunicaci\u00f3n deja de ser autom\u00e1tica y se convierte en un acto de cuidado.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal vez la inteligencia artificial no puede ense\u00f1arnos a ser humanos, pero s\u00ed puede ayudarnos a detenernos, a escuchar y a comprender que en la forma en que hablamos tambi\u00e9n se construyen v\u00ednculos, memoria y bienestar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Referencia principal&nbsp;<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Fabi\u00e1n Acevedo , L., &amp; Mireles Amador, T. P. (2026).<a href=\"https:\/\/ciencialatina.org\/index.php\/cienciala\/article\/view\/23116\" target=\"_blank\" rel=\"noreferrer noopener\"> Generaci\u00f3n de audios con intenci\u00f3n comunicativa en interacci\u00f3n con la inteligencia artificial.<\/a> <em>Ciencia Latina Revista Cient\u00edfica Multidisciplinar<\/em>, <em>10<\/em>(2), 616-641.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Autoras<\/strong><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lidia Fabi\u00e1n&nbsp;Acevedo. <\/strong>Profesora de la Preparatoria del Tecnol\u00f3gico de Monterrey Campus CDMX, desde hace dos d\u00e9cadas. Docente apasionada de las letras, la historia y la educaci\u00f3n. Ha explorado el v\u00ednculo entre literatura, cultura y docencia. Su trabajo ha sido publicado en distintas revistas acad\u00e9micas y culturales. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Tania Mireles Amador<\/strong>. Es profesora de espa\u00f1ol y literatura en la Preparatoria del Tec de Monterrey, Campus Sonora Norte. Docente interesada en literatura, \u00e9tica, feminismo e innovaci\u00f3n educativa. Ha colaborado en proyectos de investigaci\u00f3n y formaci\u00f3n relacionados con identidad, feminismo, migraci\u00f3n y violencia pol\u00edtica en medios de comunicaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.<\/p>\n","protected":false},"author":18,"featured_media":186098,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[974],"tags":[962,200,244],"class_list":["post-186095","divulgacion-ciencia","type-divulgacion-ciencia","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion-y-humanismo","tag-educacion-y-humanismo","tag-innovacion-educativa","tag-inteligencia-artificial"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Voz artificial: entre la IA y lo humano | TecScience<\/title>\n<meta name=\"description\" content=\"Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPuede una voz artificial ense\u00f1arnos a hablar con intenci\u00f3n?\" \/>\n<meta property=\"og:description\" content=\"Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/\" \/>\n<meta property=\"og:site_name\" content=\"TecScience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TecScienceWeb\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T23:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/07\/voz-artificial-y-aprendizaje.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/\",\"name\":\"Voz artificial: entre la IA y lo humano | TecScience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/voz-artificial-y-aprendizaje.jpg\",\"datePublished\":\"2026-07-11T22:14:02+00:00\",\"dateModified\":\"2026-07-13T23:02:14+00:00\",\"description\":\"Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/voz-artificial-y-aprendizaje.jpg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/07\\\/voz-artificial-y-aprendizaje.jpg\",\"width\":750,\"height\":500,\"caption\":\"La inteligencia artificial puede convertirse en una herramienta para analizar c\u00f3mo la entonaci\u00f3n, las pausas y el ritmo influyen en la forma en que nos comunicamos. (Ilustraci\u00f3n: Getty Images)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-ciencia\\\/voz-artificial-y-aprendizaje\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Divulgacion Cientifica\",\"item\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/divulgacion-cientifica\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00bfPuede una voz artificial ense\u00f1arnos a hablar con intenci\u00f3n?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"name\":\"TecScience\",\"description\":\"Bilingual platform in charge of communicating advances in research, science and innovation at Tec\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\",\"name\":\"TecScience\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"width\":250,\"height\":38,\"caption\":\"TecScience\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TecScienceWeb\",\"https:\\\/\\\/x.com\\\/TecScience_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tec-science\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tecscienceweb\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/guia-de-publicacion-para-articulos-de-divulgacion\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/equipo-editorial-tecscience\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Voz artificial: entre la IA y lo humano | TecScience","description":"Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPuede una voz artificial ense\u00f1arnos a hablar con intenci\u00f3n?","og_description":"Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.","og_url":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/","og_site_name":"TecScience","article_publisher":"https:\/\/www.facebook.com\/TecScienceWeb","article_modified_time":"2026-07-13T23:02:14+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/07\/voz-artificial-y-aprendizaje.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TecScience_","twitter_misc":{"Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/","url":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/","name":"Voz artificial: entre la IA y lo humano | TecScience","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/#primaryimage"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/07\/voz-artificial-y-aprendizaje.jpg","datePublished":"2026-07-11T22:14:02+00:00","dateModified":"2026-07-13T23:02:14+00:00","description":"Un estudio con alumnos de preparatoria muestra que escuchar versiones de su voz creadas con IA les ayuda a comunicarse de forma m\u00e1s consciente, expresiva y con intenci\u00f3n.","breadcrumb":{"@id":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/#primaryimage","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/07\/voz-artificial-y-aprendizaje.jpg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/07\/voz-artificial-y-aprendizaje.jpg","width":750,"height":500,"caption":"La inteligencia artificial puede convertirse en una herramienta para analizar c\u00f3mo la entonaci\u00f3n, las pausas y el ritmo influyen en la forma en que nos comunicamos. (Ilustraci\u00f3n: Getty Images)"},{"@type":"BreadcrumbList","@id":"https:\/\/tecscience.tec.mx\/es\/divulgacion-ciencia\/voz-artificial-y-aprendizaje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecscience.tec.mx\/es\/"},{"@type":"ListItem","position":2,"name":"Divulgacion Cientifica","item":"https:\/\/tecscience.tec.mx\/es\/divulgacion-cientifica\/"},{"@type":"ListItem","position":3,"name":"\u00bfPuede una voz artificial ense\u00f1arnos a hablar con intenci\u00f3n?"}]},{"@type":"WebSite","@id":"https:\/\/tecscience.tec.mx\/es\/#website","url":"https:\/\/tecscience.tec.mx\/es\/","name":"TecScience","description":"Bilingual platform in charge of communicating advances in research, science and innovation at Tec","publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecscience.tec.mx\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tecscience.tec.mx\/es\/#organization","name":"TecScience","url":"https:\/\/tecscience.tec.mx\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","width":250,"height":38,"caption":"TecScience"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TecScienceWeb","https:\/\/x.com\/TecScience_","https:\/\/www.linkedin.com\/company\/tec-science\/","https:\/\/www.instagram.com\/tecscienceweb\/"],"publishingPrinciples":"https:\/\/tecscience.tec.mx\/es\/guia-de-publicacion-para-articulos-de-divulgacion\/","correctionsPolicy":"https:\/\/tecscience.tec.mx\/es\/equipo-editorial-tecscience\/"}]}},"_links":{"self":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/divulgacion-ciencia\/186095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/divulgacion-ciencia"}],"about":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/types\/divulgacion-ciencia"}],"author":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/users\/18"}],"version-history":[{"count":3,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/divulgacion-ciencia\/186095\/revisions"}],"predecessor-version":[{"id":186119,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/divulgacion-ciencia\/186095\/revisions\/186119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media\/186098"}],"wp:attachment":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media?parent=186095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/categories?post=186095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/tags?post=186095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}