{"id":133342,"date":"2021-12-23T12:43:11","date_gmt":"2021-12-23T18:43:11","guid":{"rendered":"https:\/\/tecreview.tec.mx\/?p=133342"},"modified":"2023-08-05T00:27:05","modified_gmt":"2023-08-05T00:27:05","slug":"educacion-hibrida-y-flexible","status":"publish","type":"post","link":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/","title":{"rendered":"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u201cLa pandemia nos mostr\u00f3 que el mundo va el doble de r\u00e1pido de lo que imagin\u00e1bamos\u201d, analiza<strong> Juan Freire, vicerrector de innovaci\u00f3n y transformaci\u00f3n de<a href=\"http:\/\/www.tecmilenio.mx\" target=\"_blank\" rel=\"noopener\"> Universidad Tecmilenio.<\/a><\/strong><\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">En el futuro, Freire ve una <strong>educaci\u00f3n h\u00edbrida<\/strong>, personalizada, con algunos procesos automatizados utilizando la inteligencia artificial.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">S\u00ed digital, pero que aleja a la gente de las pantallas. \u201cQue sea digital no quiere decir que est\u00e9s conectado todo el d\u00eda, sino que tienes que aprender de forma activa\u201d, explica.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Adem\u00e1s cree que el estudiante debe ir al centro de la ecuaci\u00f3n para que obtenga un <strong>aprendizaje activo<\/strong>. En entrevista con <strong><em>TecScience <\/em><\/strong>explica los detalles de la ense\u00f1anza del futuro y el nuevo papel de los educadores.&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Educaci\u00f3n h\u00edbrida y flexible<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\"><a href=\"https:\/\/juanfreire.com\/bio\/\" target=\"_blank\" rel=\"noopener\">Freire<\/a> ya ha comenzado a trabajar en el componente h\u00edbrido y flexible. \u201cEso significa que siempre va a tener elementos presenciales y digitales, estos van a combinarse de formas diferentes en funci\u00f3n de las necesidades y los objetivos de las personas\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Para el vicerrector de innovaci\u00f3n y transformaci\u00f3n de <strong>Universidad Tecmilenio<\/strong>, la presencialidad va a seguir siendo un valor muy importante para realizar procesos de relaci\u00f3n con los otros.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">El reto para la universidad es dise\u00f1ar planes educativos para que la gente pueda elegir de manera flexible, \u201c<strong>nuestra utop\u00eda es la personalizaci\u00f3n<\/strong> y ya trabajamos en eso\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Da un ejemplo: no es lo mismo un chico que dedica todo su tiempo a la universidad y tiene disponibilidad para ir al campus seis horas al d\u00eda que un adulto que trabaja y que su tiempo para la educaci\u00f3n son \u2013tan solo\u2013 unas pocas horas al d\u00eda y dispersas, quiz\u00e1 puede ir al campus un s\u00e1bado, o solo puede ir un d\u00eda por la tarde.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">&nbsp;<\/span><span style=\"font-weight: 400\">\u201cLas universidades tienen que ser capaces de dise\u00f1ar experiencias adecuadas para esa persona\u201d. A esto es a lo que Freire se refiere como \u201cponer al centro al estudiante\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">El modelo debe permitir que millones de personas personalicen el aprendizaje y eso no implique una carga de trabajo desmedida.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u201cPor ello es necesario<strong> entender la educaci\u00f3n como un servicio digital<\/strong>\u201d, para Freire se puede explicar con un caso bien conocido.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Uber es considerado un servicio digital aunque en realidad lo que gestiona es un servicio presencial. <\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u201cAc\u00e1 pasa lo mismo. El proceso educativo puede suceder en el campus, en un espacio f\u00edsico, pero la educaci\u00f3n \u2013en s\u00ed misma\u2013 es un <strong>servicio digital<\/strong>\u201d.<\/span><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter wp-image-133344 size-full\"><picture>\r\n                <source srcset=\"https:\/\/tecreview.tec.mx\/wp-content\/uploads\/2021\/12\/EA61C84B-CAC8-4E1B-B7BE-366F5C9E1B74.webp\" type=\"image\/webp\">\r\n                <img decoding=\"async\" src=\"https:\/\/tecreview.tec.mx\/wp-content\/uploads\/2021\/12\/EA61C84B-CAC8-4E1B-B7BE-366F5C9E1B74.jpg\" alt=\"La educaci\u00f3n de futuro\" class=\"wp-image-133344\"\/>\r\n            <\/picture><figcaption class=\"wp-element-caption\"><em>En el mundo digital la experiencia de usuario lo es todo, y en la educaci\u00f3n no es diferente (Captura de pantalla de la entrevista con Juan Freire v\u00eda Zoom)<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Inteligencia artificial y ciencia de datos<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Freire cofund\u00f3 10 empresas y <strong><em>startups<\/em><\/strong> dedicadas a la gesti\u00f3n ambiental, educaci\u00f3n, tecnolog\u00eda y dise\u00f1o, y consultor\u00eda estrat\u00e9gica y de innovaci\u00f3n. Y su experiencia le dice que \u201clo de hoy y del futuro son los datos\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Las universidades y todo el proceso educativo genera datos que, hasta ahora, no se han utilizado m\u00e1s para una gesti\u00f3n administrativa.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u201c<strong>Los datos son el nuevo petr\u00f3leo<\/strong>. Es la nueva base sobre la que t\u00fa vas a desarrollar inteligencia y esa inteligencia te va a permitir innovar\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">En el caso de la Universidad Tecmilenio ya han resuelto c\u00f3mo explotar los datos, para aumentar la eficiencia de los procesos, es decir, poder llegar a m\u00e1s gente.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Y, para mejorar la propia experiencia educativa, se busca que la data informe en tiempo real c\u00f3mo es la experiencia, si la gente est\u00e1 aprendiendo, si est\u00e1 satisfecha y, de esta manera, intervenir inmediatamente.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">El experto en educaci\u00f3n y aprendizaje predice que algunas funciones de educador tambi\u00e9n cambiar\u00e1n.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u201c<strong>Algunas funciones del educador van a ser sustituidas por algoritmos<\/strong> y eso podr\u00eda darnos miedo, pero yo no lo veo como algo negativo. Lo veo como la probabilidad de automatizar procesos y liberar tiempo para que se concentren en lo que realmente aporta valor\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los educadores ser\u00e1n 360, tendr\u00e1n nuevas funciones y quiz\u00e1s la menos importante ser\u00e1 el rol tradicional de transmisor de conocimientos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero surge un nuevo rol, el de <strong>acompa\u00f1ador<\/strong>, quien ayuda a formular preguntas buenas, pero no te da la respuesta<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n habr\u00e1 creadores especializados en dise\u00f1ar y producir contenidos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>En busca de experiencias de aprendizaje<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Juan Freire es cofundador <a href=\"https:\/\/www.teamlabs.es\/es\" target=\"_blank\" rel=\"noopener\">Teamlabs<\/a>, una empresa dedicada a la creaci\u00f3n de laboratorios y <strong>experiencias de aprendizaje<\/strong> que es parte de la red internacional de<strong> educaci\u00f3n emprendedora<\/strong> Mondragon Team Academy.<\/span><span style=\"font-weight: 400\">&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Define como experiencias de aprendizaje al dise\u00f1o que coloca al que aprende en el centro sin olvidar los objetivos de aprendizaje.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">\u201cEn el mundo digital la experiencia de usuario lo es todo, y en la educaci\u00f3n no es diferente\u201d, dice.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Para Freire, \u201c<strong>la experiencia es parte del resultado<\/strong>\u201d. Y funciona bajo una l\u00f3gica sencilla, si te atienden bien en el hospital, vas a mejorar m\u00e1s r\u00e1pido.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Freire sugiere que las universidades trabajen con una mentalidad de dise\u00f1o de servicios.&nbsp;<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">De hecho, se plante\u00f3 el reto de <strong>crear una educaci\u00f3n digital que aleje a la gente de las pantallas,<\/strong> \u201ceso significa que tienes que resolver problemas, retos, desarrollar proyectos y sobre todo trabajar con otros en colaboraci\u00f3n con otras personas\u201d, dice.<\/span><span style=\"font-weight: 400\">&nbsp;<\/span><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span style=\"font-weight: 400\">Un aprendizaje activo basado en la pasi\u00f3n<\/span><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">Uno de los vicios m\u00e1s grandes de las escuelas latina es que la gente no sabe trabajar en equipo, \u201chay que romper con eso y aprovechar las comunidades digitales como un canal para llegar a lo presencial\u201d.<\/span><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><span style=\"font-weight: 400\">En ese sentido, Freire explica que en el futuro los campus dejar\u00e1n de ser una colecci\u00f3n de aulas y se convertir\u00e1n en espacios para trabajar y hacer comunidad.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores<\/p>\n","protected":false},"author":8,"featured_media":156178,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[101],"tags":[],"class_list":["post-133342","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-humano-social"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La educaci\u00f3n del futuro es digital | TecScience<\/title>\n<meta name=\"description\" content=\"En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla\" \/>\n<meta property=\"og:description\" content=\"En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/\" \/>\n<meta property=\"og:site_name\" content=\"TecScience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TecScienceWeb\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-23T18:43:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-05T00:27:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/educacion-hibrida-y-flexible.png\" \/>\n\t<meta property=\"og:image:width\" content=\"633\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Susan Irais\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:site\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Susan Irais\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/\"},\"author\":{\"name\":\"Susan Irais\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/34a3de1490dbfc4b7e6fdd77527eb948\"},\"headline\":\"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla\",\"datePublished\":\"2021-12-23T18:43:11+00:00\",\"dateModified\":\"2023-08-05T00:27:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/\"},\"wordCount\":996,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/12\\\/educacion-hibrida-y-flexible.png\",\"articleSection\":[\"Humano y Social\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/\",\"name\":\"La educaci\u00f3n del futuro es digital | TecScience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/12\\\/educacion-hibrida-y-flexible.png\",\"datePublished\":\"2021-12-23T18:43:11+00:00\",\"dateModified\":\"2023-08-05T00:27:05+00:00\",\"description\":\"En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/12\\\/educacion-hibrida-y-flexible.png\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2021\\\/12\\\/educacion-hibrida-y-flexible.png\",\"width\":633,\"height\":433,\"caption\":\"La educaci\u00f3n del futuro que ya lleg\u00f3 exige que las universidades dise\u00f1en experiencias adecuadas para cada persona. (Ilustraci\u00f3n: iStock)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/humano-social\\\/educacion-hibrida-y-flexible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"name\":\"TecScience\",\"description\":\"Bilingual platform in charge of communicating advances in research, science and innovation at Tec\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\",\"name\":\"TecScience\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"width\":250,\"height\":38,\"caption\":\"TecScience\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TecScienceWeb\",\"https:\\\/\\\/x.com\\\/TecScience_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tec-science\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tecscienceweb\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/guia-de-publicacion-para-articulos-de-divulgacion\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/equipo-editorial-tecscience\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/34a3de1490dbfc4b7e6fdd77527eb948\",\"name\":\"Susan Irais\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89725ba68bb7e33a2fcc2280851cebbae9b21ad33132c06660766edf5785b7ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89725ba68bb7e33a2fcc2280851cebbae9b21ad33132c06660766edf5785b7ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/89725ba68bb7e33a2fcc2280851cebbae9b21ad33132c06660766edf5785b7ff?s=96&d=mm&r=g\",\"caption\":\"Susan Irais\"},\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/author\\\/sirais\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La educaci\u00f3n del futuro es digital | TecScience","description":"En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/","og_locale":"es_ES","og_type":"article","og_title":"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla","og_description":"En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores","og_url":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/","og_site_name":"TecScience","article_publisher":"https:\/\/www.facebook.com\/TecScienceWeb","article_published_time":"2021-12-23T18:43:11+00:00","article_modified_time":"2023-08-05T00:27:05+00:00","og_image":[{"width":633,"height":433,"url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/educacion-hibrida-y-flexible.png","type":"image\/png"}],"author":"Susan Irais","twitter_card":"summary_large_image","twitter_creator":"@TecScience_","twitter_site":"@TecScience_","twitter_misc":{"Escrito por":"Susan Irais","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#article","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/"},"author":{"name":"Susan Irais","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/34a3de1490dbfc4b7e6fdd77527eb948"},"headline":"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla","datePublished":"2021-12-23T18:43:11+00:00","dateModified":"2023-08-05T00:27:05+00:00","mainEntityOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/"},"wordCount":996,"commentCount":0,"publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/educacion-hibrida-y-flexible.png","articleSection":["Humano y Social"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/","url":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/","name":"La educaci\u00f3n del futuro es digital | TecScience","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#primaryimage"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/educacion-hibrida-y-flexible.png","datePublished":"2021-12-23T18:43:11+00:00","dateModified":"2023-08-05T00:27:05+00:00","description":"En el futuro la educaci\u00f3n ser\u00e1 h\u00edbrida, personalizada y la inteligencia artificial sustituir\u00e1 algunos procesos de los educadores","breadcrumb":{"@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#primaryimage","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/educacion-hibrida-y-flexible.png","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2021\/12\/educacion-hibrida-y-flexible.png","width":633,"height":433,"caption":"La educaci\u00f3n del futuro que ya lleg\u00f3 exige que las universidades dise\u00f1en experiencias adecuadas para cada persona. (Ilustraci\u00f3n: iStock)"},{"@type":"BreadcrumbList","@id":"https:\/\/tecscience.tec.mx\/es\/humano-social\/educacion-hibrida-y-flexible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecscience.tec.mx\/es\/"},{"@type":"ListItem","position":2,"name":"La educaci\u00f3n del futuro es digital, pero lejos de la pantalla"}]},{"@type":"WebSite","@id":"https:\/\/tecscience.tec.mx\/es\/#website","url":"https:\/\/tecscience.tec.mx\/es\/","name":"TecScience","description":"Bilingual platform in charge of communicating advances in research, science and innovation at Tec","publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecscience.tec.mx\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tecscience.tec.mx\/es\/#organization","name":"TecScience","url":"https:\/\/tecscience.tec.mx\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","width":250,"height":38,"caption":"TecScience"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TecScienceWeb","https:\/\/x.com\/TecScience_","https:\/\/www.linkedin.com\/company\/tec-science\/","https:\/\/www.instagram.com\/tecscienceweb\/"],"publishingPrinciples":"https:\/\/tecscience.tec.mx\/es\/guia-de-publicacion-para-articulos-de-divulgacion\/","correctionsPolicy":"https:\/\/tecscience.tec.mx\/es\/equipo-editorial-tecscience\/"},{"@type":"Person","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/34a3de1490dbfc4b7e6fdd77527eb948","name":"Susan Irais","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/89725ba68bb7e33a2fcc2280851cebbae9b21ad33132c06660766edf5785b7ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/89725ba68bb7e33a2fcc2280851cebbae9b21ad33132c06660766edf5785b7ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/89725ba68bb7e33a2fcc2280851cebbae9b21ad33132c06660766edf5785b7ff?s=96&d=mm&r=g","caption":"Susan Irais"},"url":"https:\/\/tecscience.tec.mx\/es\/author\/sirais\/"}]}},"_links":{"self":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/133342","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/comments?post=133342"}],"version-history":[{"count":0,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/133342\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media\/156178"}],"wp:attachment":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media?parent=133342"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/categories?post=133342"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/tags?post=133342"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}