{"id":165824,"date":"2024-07-03T13:52:32","date_gmt":"2024-07-03T19:52:32","guid":{"rendered":"https:\/\/tecscience.tec.mx\/es\/?p=165824"},"modified":"2024-12-12T11:43:05","modified_gmt":"2024-12-12T17:43:05","slug":"como-hacer-bolsas-de-plastico-biodegradables","status":"publish","type":"post","link":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/","title":{"rendered":"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Eliminar las bolsas de pl\u00e1stico es un objetivo dif\u00edcil de alcanzar. A muchos nos pasa que cuando llega la hora de recoger las heces de nuestras mascotas, por ejemplo, no encontramos una alternativa igual de funcional. Hacerle un nudo a una bolsa de cart\u00f3n resulta complicado. Para esto existen las bolsas creadas con pl\u00e1sticos sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cUna vez desechadas, estas se degradan en un periodo mucho m\u00e1s corto y pueden servir de abono para nutrir a las plantas o la tierra\u201d, dice <a href=\"https:\/\/research.tec.mx\/vivo-tec\/display\/PID_294635?_gl=1*1uka5vd*_gcl_au*MTg4NDkwMDQ5Ny4xNzE4OTM2MDc0LjE4MTU3NTU3NDYuMTcxOTI2MzQyNy4xNzE5MjYzNDI3*_ga*ODI2ODY4NzY5LjE3MTg5MzYwNzQ.*_ga_D9LSDN87GD*MTcxOTI2MzI1Ni40LjEuMTcxOTI2MzQzNS40Ny4wLjM0NTgxNDI4NQ..\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Dora Iliana Medina<\/strong><\/a>, l\u00edder de la Accelerate Materials Development Unit del <a href=\"https:\/\/tec.mx\/en\/research\/institute-advanced-materials-sustainable-manufacturing\" target=\"_blank\" rel=\"noreferrer noopener\">Institute of Advanced Materials for Sustainable Manufacturing<\/a> (IAMSM) del Tec de Monterrey.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La necesidad de encontrar materiales que reemplacen <a href=\"\/es\/biotecnologia\/solucion-a-la-crisis-del-plastico\/\" target=\"_blank\" rel=\"noreferrer noopener\">el pl\u00e1stico tradicional <\/a>se debe a que este es creado a partir del petr\u00f3leo, lo cual ocasiona que tarden mucho tiempo en degradarse, con estimaciones de entre 150 y 500 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El que sean tan resistentes ha resultado en que contaminen las ciudades y ecosistemas del planeta, con los acu\u00e1ticos siendo entre los m\u00e1s afectados.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los animales, silvestres y dom\u00e9sticos, pueden consumirlas accidentalmente, lo cu\u00e1l amenaza su vida. \u201cSon letales para las tortugas, las ballenas y los delfines porque se las tragan o pueden enredarse en ellas\u201d, explica Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los <a href=\"\/es\/salud\/microplasticos-en-la-leche-humana\/\" target=\"_blank\" rel=\"noreferrer noopener\">micropl\u00e1sticos<\/a> y las emisiones t\u00f3xicas que resultan de quemarlas tambi\u00e9n forman parte de esta problem\u00e1tica.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de esto, en el mundo se usan alrededor de 500,000 millones de bolsas de pl\u00e1stico al a\u00f1o, <a href=\"https:\/\/news.un.org\/es\/story\/2019\/03\/1452961\" target=\"_blank\" rel=\"noreferrer noopener\">de acuerdo con estimaciones de la Organizaci\u00f3n de las Naciones Unidas<\/a> (ONU). <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMuchas siguen siendo desechadas despu\u00e9s de un solo uso\u201d, dice la experta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, a nivel global, se han tomado medidas para reducir su uso, frenar su producci\u00f3n y reemplazarlas con unas hechas a partir de materiales biodegradables.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"El pl\u00e1stico no es el enemigo \ud83d\udc40\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/Txatr1k64Vs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>C\u00f3mo hacer bolsas de pl\u00e1stico biodegradables<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Hace algunos a\u00f1os, en los supermercados se hab\u00edan empezado a empaquetar los alimentos con bolsas que dec\u00edan ser biodegradables, sin embargo, la mayor\u00eda no cumpl\u00edan con las regulaciones necesarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cMucho del material con el que eran hechas segu\u00eda siendo con derivados del petr\u00f3leo\u201d, explica Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como respuesta ante esto, en la Ciudad de M\u00e9xico, a partir del 2021, entr\u00f3 en vigor la <a href=\"https:\/\/congresocdmx.gob.mx\/comsoc-diputados-prohiben-venta-productos-plasticos-solo-uso-cdmx-las-empresas-tendran-que-fabricar-articulos-biodegradables-1466-1.html\" target=\"_blank\" rel=\"noreferrer noopener\">prohibici\u00f3n de uso de pl\u00e1sticos y desechables de un solo uso<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es por ello que hoy, cuando vamos al supermercado encontramos bolsas de cart\u00f3n en vez de bolsas de pl\u00e1stico para transportar frutas y verduras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, muchos seguimos encontrando la forma de acceder a bolsas de pl\u00e1stico para usarlas para deshacernos de nuestra basura org\u00e1nica o recoger los desechos de nuestras mascotas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cComo humanidad hemos creado un h\u00e1bito en el que dependemos de las bolsas de pl\u00e1stico\u201d, dice la investigadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto se debe a muchos factores, pero el hecho de que los consumidores las preferimos para algunas tareas espec\u00edficas tiene mucho que ver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para la experta, esto se debe en gran parte a las propiedades de las bolsas hechas con polietileno, el tipo de pl\u00e1stico m\u00e1s com\u00fan que se utiliza en la actualidad. Este es flexible, resistente, impermeable, ligero y vers\u00e1til, por lo que las bolsas hechas con \u00e9l resultan demasiado c\u00f3modas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un material muy estudiado, f\u00e1cil de procesar y, adem\u00e1s, barato\u201d, explica Medina.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Ep. 79 - Bioempaques: Sustitutos del pl\u00e1stico amigables con el ambiente\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/0Kt1JIpuHMxjVIyaQpAsjS?si=Ig--2_wRQvODnaBfue57jQ&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un proyecto que busca crear un pl\u00e1stico verdaderamente biodegradable y sostenible<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Encontrar un material que sea igual de conveniente y accesible que el polietileno es un reto para quienes buscan crear pl\u00e1sticos sostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la unidad liderada por Medina, durante los \u00faltimos a\u00f1os, uno de sus <a href=\"https:\/\/onlinelibrary.wiley.com\/doi\/abs\/10.1002\/bip.23585\" target=\"_blank\" rel=\"noreferrer noopener\">principales proyectos<\/a> ha sido producir un pl\u00e1stico a partir de desechos vegetales, como los granos de caf\u00e9, para crear bolsas con propiedades similares a las tradicionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para lograrlo, mezclan alcohol polivinilico \u2212un pol\u00edmero soluble en agua\u2212, quitosano \u2212un biopol\u00edmero\u2212 y holocelulosa \u2212un tipo espec\u00edfico de celulosa\u2212 extra\u00edda de granos de caf\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al mezclar los tres elementos, obtienen una pel\u00edcula delgada que puede utilizarse como alternativa para crear empaques y bolsas verdaderamente biodegradables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAl desecharse, se descompone en sus componentes principales, la celulosa, la cu\u00e1l nutre a las plantas, pero adem\u00e1s tiene propiedades antioxidantes que pueden contribuir a la salud de los suelos\u201d, cuenta Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por el momento, <a href=\"https:\/\/chemistry-europe.onlinelibrary.wiley.com\/doi\/abs\/10.1002\/slct.202304199\" target=\"_blank\" rel=\"noreferrer noopener\">han logrado comprobar<\/a> que el pl\u00e1stico que obtienen tiene una estructura macro y microsc\u00f3pica con propiedades que le permiten repeler el agua, manteniendo la suficiente firmeza y flexibilidad, para que la bolsa sea manipulable, pero no se rompa al contacto con alg\u00fan l\u00edquido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el futuro pr\u00f3ximo, planean empezar a probar este material en bolsas para comprobar que son una alternativa funcional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si la tecnolog\u00eda resulta exitosa, esta podr\u00eda aplicarse tambi\u00e9n con desechos org\u00e1nicos como c\u00e1scaras de aguacate, de naranja o sobras de la ca\u00f1a de az\u00facar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCreo que el hecho de que los desperdicios sean nuestra materia prima y, adem\u00e1s, el pl\u00e1stico que creamos no le hace da\u00f1o al ambiente es algo muy positivo\u201d, dice Medina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mientras siguen los pasos necesarios para crear un producto que sea asequible para las empresas y escalable a nivel industrial, los ciudadanos podemos optar por reducir el uso de las bolsas de pl\u00e1stico lo m\u00e1s que podamos y reusar las bolsas cuanto m\u00e1s nos sea posible.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00bfTe interes\u00f3 esta historia? \u00bfQuieres publicarla?\u00a0 Contacta a nuestra editora de contenidos para conocer m\u00e1s\u00a0<a href=\"mailto:marianaleonm@tec.mx\" target=\"_blank\" rel=\"noreferrer noopener\">marianaleonm@tec.mx<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables<\/p>\n","protected":false},"author":12,"featured_media":166044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[98],"tags":[110,474],"class_list":["post-165824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-institute-of-advanced-materials-for-sustainable-manufacturing","tag-tecnologia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C\u00f3mo hacer bolsas de pl\u00e1stico biodegradables | TecScience<\/title>\n<meta name=\"description\" content=\"Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables\" \/>\n<meta property=\"og:description\" content=\"Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/\" \/>\n<meta property=\"og:site_name\" content=\"TecScience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TecScienceWeb\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-03T19:52:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-12T17:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2024\/06\/como-hacer-bolsas-de-plastico-biodegradables.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"In\u00e9s Guti\u00e9rrez Jaber\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:site\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"In\u00e9s Guti\u00e9rrez Jaber\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/\"},\"author\":{\"name\":\"In\u00e9s Guti\u00e9rrez Jaber\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/72a3b50d0dbd7d1124452069e14a2db9\"},\"headline\":\"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables\",\"datePublished\":\"2024-07-03T19:52:32+00:00\",\"dateModified\":\"2024-12-12T17:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/\"},\"wordCount\":959,\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/06\\\/como-hacer-bolsas-de-plastico-biodegradables.jpg\",\"keywords\":[\"Institute of Advanced Materials for Sustainable Manufacturing\",\"Tecnolog\u00eda\"],\"articleSection\":[\"Tecnolog\u00eda\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/\",\"name\":\"C\u00f3mo hacer bolsas de pl\u00e1stico biodegradables | TecScience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/06\\\/como-hacer-bolsas-de-plastico-biodegradables.jpg\",\"datePublished\":\"2024-07-03T19:52:32+00:00\",\"dateModified\":\"2024-12-12T17:43:05+00:00\",\"description\":\"Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/06\\\/como-hacer-bolsas-de-plastico-biodegradables.jpg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2024\\\/06\\\/como-hacer-bolsas-de-plastico-biodegradables.jpg\",\"width\":750,\"height\":500,\"caption\":\"En el futuro pr\u00f3ximo, planean empezar a probar este material en bolsas para comprobar que son una alternativa funcional. (Foto: Getty Images)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/tecnologia\\\/como-hacer-bolsas-de-plastico-biodegradables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"name\":\"TecScience\",\"description\":\"Bilingual platform in charge of communicating advances in research, science and innovation at Tec\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\",\"name\":\"TecScience\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"width\":250,\"height\":38,\"caption\":\"TecScience\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TecScienceWeb\",\"https:\\\/\\\/x.com\\\/TecScience_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tec-science\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tecscienceweb\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/guia-de-publicacion-para-articulos-de-divulgacion\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/equipo-editorial-tecscience\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/72a3b50d0dbd7d1124452069e14a2db9\",\"name\":\"In\u00e9s Guti\u00e9rrez Jaber\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d136e90158f5aac8a8da8abe38806ceebb853d4d6d17967fb867b912b35483a9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d136e90158f5aac8a8da8abe38806ceebb853d4d6d17967fb867b912b35483a9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d136e90158f5aac8a8da8abe38806ceebb853d4d6d17967fb867b912b35483a9?s=96&d=mm&r=g\",\"caption\":\"In\u00e9s Guti\u00e9rrez Jaber\"},\"description\":\"Periodista de ciencia y artista visual. Mi trabajo ha sido publicado en medios como Science, Science News, Newsweek, Nexos, \u00bfC\u00f3mo ves?, entre otros. Estudi\u00e9 Biolog\u00eda en la Facultad de Ciencias de la UNAM y ah\u00ed descubr\u00ed mi pasi\u00f3n por comunicarle a todas las personas el conocimiento cient\u00edfico y su relevancia social. Creo que la ciencia, al fomentar el pensamiento cr\u00edtico, puede empoderar a la humanidad y, al ser la base de los avances tecnol\u00f3gicos, puede ayudarla a vivir en las mejores condiciones posibles.\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/author\\\/igutierrez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C\u00f3mo hacer bolsas de pl\u00e1stico biodegradables | TecScience","description":"Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables","og_description":"Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables","og_url":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/","og_site_name":"TecScience","article_publisher":"https:\/\/www.facebook.com\/TecScienceWeb","article_published_time":"2024-07-03T19:52:32+00:00","article_modified_time":"2024-12-12T17:43:05+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2024\/06\/como-hacer-bolsas-de-plastico-biodegradables.jpg","type":"image\/jpeg"}],"author":"In\u00e9s Guti\u00e9rrez Jaber","twitter_card":"summary_large_image","twitter_creator":"@TecScience_","twitter_site":"@TecScience_","twitter_misc":{"Escrito por":"In\u00e9s Guti\u00e9rrez Jaber","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#article","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/"},"author":{"name":"In\u00e9s Guti\u00e9rrez Jaber","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/72a3b50d0dbd7d1124452069e14a2db9"},"headline":"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables","datePublished":"2024-07-03T19:52:32+00:00","dateModified":"2024-12-12T17:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/"},"wordCount":959,"publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2024\/06\/como-hacer-bolsas-de-plastico-biodegradables.jpg","keywords":["Institute of Advanced Materials for Sustainable Manufacturing","Tecnolog\u00eda"],"articleSection":["Tecnolog\u00eda"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/","url":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/","name":"C\u00f3mo hacer bolsas de pl\u00e1stico biodegradables | TecScience","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#primaryimage"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2024\/06\/como-hacer-bolsas-de-plastico-biodegradables.jpg","datePublished":"2024-07-03T19:52:32+00:00","dateModified":"2024-12-12T17:43:05+00:00","description":"Un grupo de investigadores busca crear un biopl\u00e1stico a partir de desechos de plantas para producir bolsas de pl\u00e1stico biodegradables","breadcrumb":{"@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#primaryimage","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2024\/06\/como-hacer-bolsas-de-plastico-biodegradables.jpg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2024\/06\/como-hacer-bolsas-de-plastico-biodegradables.jpg","width":750,"height":500,"caption":"En el futuro pr\u00f3ximo, planean empezar a probar este material en bolsas para comprobar que son una alternativa funcional. (Foto: Getty Images)"},{"@type":"BreadcrumbList","@id":"https:\/\/tecscience.tec.mx\/es\/tecnologia\/como-hacer-bolsas-de-plastico-biodegradables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecscience.tec.mx\/es\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo hacer bolsas de pl\u00e1stico (realmente) biodegradables"}]},{"@type":"WebSite","@id":"https:\/\/tecscience.tec.mx\/es\/#website","url":"https:\/\/tecscience.tec.mx\/es\/","name":"TecScience","description":"Bilingual platform in charge of communicating advances in research, science and innovation at Tec","publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecscience.tec.mx\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tecscience.tec.mx\/es\/#organization","name":"TecScience","url":"https:\/\/tecscience.tec.mx\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","width":250,"height":38,"caption":"TecScience"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TecScienceWeb","https:\/\/x.com\/TecScience_","https:\/\/www.linkedin.com\/company\/tec-science\/","https:\/\/www.instagram.com\/tecscienceweb\/"],"publishingPrinciples":"https:\/\/tecscience.tec.mx\/es\/guia-de-publicacion-para-articulos-de-divulgacion\/","correctionsPolicy":"https:\/\/tecscience.tec.mx\/es\/equipo-editorial-tecscience\/"},{"@type":"Person","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/72a3b50d0dbd7d1124452069e14a2db9","name":"In\u00e9s Guti\u00e9rrez Jaber","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d136e90158f5aac8a8da8abe38806ceebb853d4d6d17967fb867b912b35483a9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d136e90158f5aac8a8da8abe38806ceebb853d4d6d17967fb867b912b35483a9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d136e90158f5aac8a8da8abe38806ceebb853d4d6d17967fb867b912b35483a9?s=96&d=mm&r=g","caption":"In\u00e9s Guti\u00e9rrez Jaber"},"description":"Periodista de ciencia y artista visual. Mi trabajo ha sido publicado en medios como Science, Science News, Newsweek, Nexos, \u00bfC\u00f3mo ves?, entre otros. Estudi\u00e9 Biolog\u00eda en la Facultad de Ciencias de la UNAM y ah\u00ed descubr\u00ed mi pasi\u00f3n por comunicarle a todas las personas el conocimiento cient\u00edfico y su relevancia social. Creo que la ciencia, al fomentar el pensamiento cr\u00edtico, puede empoderar a la humanidad y, al ser la base de los avances tecnol\u00f3gicos, puede ayudarla a vivir en las mejores condiciones posibles.","url":"https:\/\/tecscience.tec.mx\/es\/author\/igutierrez\/"}]}},"_links":{"self":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/165824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/comments?post=165824"}],"version-history":[{"count":0,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/165824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media\/166044"}],"wp:attachment":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media?parent=165824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/categories?post=165824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/tags?post=165824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}