{"id":178420,"date":"2025-07-07T18:17:36","date_gmt":"2025-07-08T00:17:36","guid":{"rendered":"https:\/\/tecscience.tec.mx\/es\/?p=178420"},"modified":"2025-10-07T15:56:09","modified_gmt":"2025-10-07T21:56:09","slug":"ciudades-para-la-infancia","status":"publish","type":"post","link":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/","title":{"rendered":"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En 2017, un grupo de investigadores public\u00f3 un argumento econ\u00f3mico a favor de la inversi\u00f3n en la educaci\u00f3n de <a href=\"\/es\/humano-social\/segundo-foro-internacional-de-primera-infancia\/\" target=\"_blank\" rel=\"noreferrer noopener\">temprana edad<\/a>. El equipo, que incluy\u00f3 al economista y <a href=\"\/es\/tag\/premio-nobel\/\" target=\"_blank\" rel=\"noreferrer noopener\">Premio Nobel<\/a> James Heckman, encontr\u00f3 que por cada d\u00f3lar que una persona invierte en los primeros cinco a\u00f1os de un ni\u00f1o, el retorno era de 6.30 d\u00f3lares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reporte, <a href=\"https:\/\/www.nber.org\/system\/files\/working_papers\/w22993\/w22993.pdf\">publicado por el National Bureau of Economic Research en Massachusetts, cuantific\u00f3 <strong>los beneficios desde la infancia hasta la mediana edad<\/strong> de un programa educativo para ni\u00f1os y ni\u00f1as de uno a cinco a\u00f1os<\/a>. Su enfoque fue en la educaci\u00f3n, pero como explica <a href=\"https:\/\/research.tec.mx\/vivo-tec\/display\/PID_326997\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>N\u00e9lida Escobedo<\/strong><\/a>, hay amplias oportunidades para invertir en la infancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSi como sociedades invertimos en mejorar las ciudades para este grupo poblacional, en realidad, estamos trabajando para toda la poblaci\u00f3n\u201d, explica la <strong>profesora investigadora en urbanismo social<\/strong> del <a href=\"\/es\/tag\/centro-para-el-futuro-de-las-ciudades\/\" target=\"_blank\" rel=\"noreferrer noopener\">Centro para el Futuro de las Ciudades<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta premisa, respaldada por d\u00e9cadas de investigaci\u00f3n cient\u00edfica, es el motor detr\u00e1s de <a href=\"https:\/\/urban95academy.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Urban95 Academy<\/a>, un programa que ayuda a gobiernos locales a crear <strong>estrategias para apoyar a la infancia en sus ciudades<\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En colaboraci\u00f3n con el Centro para el Futuro de las Ciudades, la Fundaci\u00f3n FEMSA, London School of Economics Cities y la Fundaci\u00f3n Van Leer se va a ofrecer este programa \u2014por primera vez\u2014 completamente <strong>en espa\u00f1ol para localidades de Am\u00e9rica Latina y el Caribe.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/urban95academy.org\/es\/registro\/\" target=\"_blank\" rel=\" noreferrer noopener\"><picture>\r\n                <source srcset=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy-1.webp\" type=\"image\/webp\">\r\n                <img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"200\" src=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy-1.jpeg\" alt=\"\" class=\"wp-image-178452\" srcset=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy-1.jpeg 600w, https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy-1-300x100.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\r\n            <\/picture><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Existen m\u00faltiples <a href=\"\/es\/humano-social\/adversidad-en-la-infancia\/\" target=\"_blank\" rel=\"noreferrer noopener\">estudios que revelan la importancia<\/a> de los primeros dos a\u00f1os de vida en el desarrollo cerebral y cognitivo. Para los cinco a\u00f1os, el cerebro ya creci\u00f3 al 90% de su tama\u00f1o. Es la etapa en donde se encuentra la mayor actividad neuronal que no se vuelve a repetir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, explica Escobedo, es importante que crezcan en un <strong>entorno que promueva esa actividad cerebral<\/strong> a trav\u00e9s de conexiones sociales. No es solo pensar en los infantes sino tambi\u00e9n <a href=\"\/es\/humano-social\/estres-de-los-cuidadores-primarios\/\" target=\"_blank\" rel=\"noreferrer noopener\">las personas que los cuidan<\/a> e interact\u00faan con ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstas interacciones suceden en la casa, en la calle, suceden en la colonia,\u201d dice la investigadora. \u201c\u00bfC\u00f3mo podemos generar ciudades que sepan que esas conexiones de cuidado y de cari\u00f1o son necesarias?\u201d<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Cuando la infancia deja cicatrices: el costo oculto del estr\u00e9s t\u00f3xico\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/3BRJrihqwdo?start=7&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo el entorno urbano afecta a la infancia?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las estrategias fundamentales es la creaci\u00f3n de <strong>espacios p\u00fablicos y parques<\/strong> para la primera edad. Pero, no lo es todo. Con Urban95 Academy, la propuesta es pensar integralmente, considerando no solo el <a href=\"\/es\/humano-social\/disminuir-la-violencia-en-las-ciudades\/\" target=\"_blank\" rel=\"noreferrer noopener\">espacio p\u00fablico<\/a>, sino tambi\u00e9n la cobertura de servicios m\u00e9dicos, escolares, espacios de recreaci\u00f3n y, fundamentalmente, el fortalecimiento del tejido social en los barrios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/c-lab.com.mx\/nosotros\/claudia-ledezma-garza\" target=\"_blank\" rel=\"noreferrer noopener\">Claudia Ledezma<\/a><\/strong>, coordinadora de proyectos para el Centro para el Futuro de las Ciudades y coordinadora de la edici\u00f3n regional de Urban95 Academy, comparti\u00f3 un ejemplo de c\u00f3mo los ni\u00f1os en particular se ven afectados por su <a href=\"\/es\/ciudades-y-comunidades-prosperas\/diseno-multiespecies\/\" target=\"_blank\" rel=\"noreferrer noopener\">entorno urbano.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace cuatro a\u00f1os, el centro organiz\u00f3 una actividad en la que se pidi\u00f3 a ni\u00f1os y ni\u00f1as representar, a trav\u00e9s de dibujos, lo que les gustaba de su barrio y lo que no. Muchos plasmaron im\u00e1genes del sol. Al visitar la comunidad donde viven, Ledezma y su equipo comprendieron que esas ilustraciones alud\u00edan al exceso de calor y a la falta de sombra o \u00e1rboles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEllos son totalmente conscientes de lo que est\u00e1n sufriendo en sus trayectos y en su vida diaria\u201d dijo Ledezma.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los retos en ciudades latinoamericanas<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Al preparar la edici\u00f3n piloto de Urban95 Academy en Latinoam\u00e9rica, no solo est\u00e1n traduciendo el programa al ingl\u00e9s. Tambi\u00e9n, est\u00e1n pensando en los obst\u00e1culos espec\u00edficos a la regi\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 81% de la poblaci\u00f3n de Am\u00e9rica Latina y el Caribe vive en una ciudad. Aunque en estas ciudades se concentre la actividad econ\u00f3mica de sus pa\u00edses, la <strong>desigualdad de ingresos<\/strong> se ha vuelto una caracter\u00edstica del entorno urbano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En <a href=\"\/es\/ciudades-y-comunidades-prosperas\/vivienda-en-mexico-autoproducida\/\" target=\"_blank\" rel=\"noreferrer noopener\">Monterrey<\/a>, por ejemplo, hay zonas de muy baja densidad que cada vez cuentan con m\u00e1s viviendas lejos de las centrales donde hay empleos, dice Escobedo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Am\u00e9rica Latina, es com\u00fan la existencia de viviendas precarias o autoproducidas, como favelas, barrios de ranco o asentamientos irregulares. Estas comunidades suelen carecer de servicios b\u00e1sicos como iluminaci\u00f3n, agua potable, drenaje y otros elementos esenciales para la vivienda digna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo esto y m\u00e1s contribuye a un <a href=\"\/es\/humano-social\/9-de-cada-10-mexicanos-vivio-experiencias-adversas-durante-su-infancia\/\" target=\"_blank\" rel=\"noreferrer noopener\">entorno estresante<\/a> tanto para los ni\u00f1os y ni\u00f1as y para los adultos que los cuidan.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: Ep. 123 - La importancia de la caminabilidad en las ciudades | La entrevista\" style=\"border-radius: 12px\" width=\"100%\" height=\"152\" frameborder=\"0\" allowfullscreen allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" src=\"https:\/\/open.spotify.com\/embed\/episode\/7iTXNeQfo0uUJE0kTTfqwB?si=c9db209a0c3245b3&#038;utm_source=oembed\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo participar en Urban95 Academy?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El programa es completamente gratuito y est\u00e1 dise\u00f1ado en varias fases. Entre <strong>30 y 50 ciudades participar\u00e1n en el componente en l\u00ednea<\/strong>, que se desarrollar\u00e1 de septiembre a noviembre de 2025. Las mejores estrategias y proyectos desarrollados ser\u00e1n seleccionados para que 10 ciudades participen en una semana de residencia en la Ciudad de M\u00e9xico, programada del 26 al 30 de enero de 2026.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta semana intensiva incluye clases, visitas de sitio, talleres y la participaci\u00f3n de profesores regionales. Finalmente, las ciudades participantes recibir\u00e1n <strong>asistencia t\u00e9cnica<\/strong> durante seis meses para desarrollar sus estrategias, proyectos o programas con el apoyo de socios t\u00e9cnicos expertos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los organizadores describen el programa como \u201cuna incubadora de estrategias de pol\u00edticas o de agenda\u201d. No se trata de implementar directamente, sino de asesorar a las ciudades en el desarrollo de pol\u00edticas p\u00fablicas y programas que respondan a sus contextos espec\u00edficos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La convocatoria est\u00e1 abierta hasta el <strong>25 de julio.<\/strong> Equipos de hasta tres personas pueden aplicar a trav\u00e9s del portal en l\u00ednea. No es necesario ser parte del gobierno local, tambi\u00e9n est\u00e1 abierto a organizaciones o planificadores urbanos que trabajan con gobiernos, pero parte de la aplicaci\u00f3n es una carta del alcalde o alg\u00fan oficial que confirme conocimiento del proyecto.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><a href=\"https:\/\/urban95academy.org\/es\/registro\/\" target=\"_blank\" rel=\" noreferrer noopener\"><picture>\r\n                <source srcset=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy.webp\" type=\"image\/webp\">\r\n                <img decoding=\"async\" width=\"600\" height=\"200\" src=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy.jpeg\" alt=\"\" class=\"wp-image-178440\" srcset=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy.jpeg 600w, https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/urban-academy-300x100.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\r\n            <\/picture><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br><em><strong>\u00bfTe interes\u00f3 esta historia? \u00bfQuieres publicarla?&nbsp; Contacta a nuestra editora de contenidos para conocer m\u00e1s&nbsp;<a href=\"mailto:marianaleonm@tec.mx\">marianaleonm@tec.mx<\/a><\/strong><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un programa gratuito ayudar\u00e1 a 30-50 proyectos a desarrollar estrategias que beneficien a ni\u00f1os y ni\u00f1as de temprana edad y sus cuidadores en su entorno. <\/p>\n","protected":false},"author":50,"featured_media":178470,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[975],"tags":[868],"class_list":["post-178420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciudades-y-comunidades-prosperas","tag-centro-para-el-futuro-de-las-ciudades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u00bfC\u00f3mo pueden mejorar las ciudades pensando en la infancia? | TecScience<\/title>\n<meta name=\"description\" content=\"\u00bfQu\u00e9 ven, sienten y necesitan ni\u00f1as y ni\u00f1os en sus ciudades? Urban95 Academy propone redise\u00f1ar el entorno a partir de sus experiencias.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfC\u00f3mo pueden mejorar las ciudades pensando en la infancia? | TecScience\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 ven, sienten y necesitan ni\u00f1as y ni\u00f1os en sus ciudades? Urban95 Academy propone redise\u00f1ar el entorno a partir de sus experiencias.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/\" \/>\n<meta property=\"og:site_name\" content=\"TecScience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TecScienceWeb\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-08T00:17:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-07T21:56:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/infancias.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nuria M\u00e1rquez Mart\u00ednez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina\" \/>\n<meta name=\"twitter:creator\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:site\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nuria M\u00e1rquez Mart\u00ednez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/\"},\"author\":{\"name\":\"Nuria M\u00e1rquez Mart\u00ednez\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/a537c370cdc578d5d7ef285ecf5b1699\"},\"headline\":\"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina\",\"datePublished\":\"2025-07-08T00:17:36+00:00\",\"dateModified\":\"2025-10-07T21:56:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/\"},\"wordCount\":1033,\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/07\\\/infancias-1.jpg\",\"keywords\":[\"Centro para el Futuro de las Ciudades\"],\"articleSection\":[\"Ciudades y Comunidades Pr\u00f3speras\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/\",\"name\":\"\u00bfC\u00f3mo pueden mejorar las ciudades pensando en la infancia? | TecScience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/07\\\/infancias-1.jpg\",\"datePublished\":\"2025-07-08T00:17:36+00:00\",\"dateModified\":\"2025-10-07T21:56:09+00:00\",\"description\":\"\u00bfQu\u00e9 ven, sienten y necesitan ni\u00f1as y ni\u00f1os en sus ciudades? Urban95 Academy propone redise\u00f1ar el entorno a partir de sus experiencias.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/07\\\/infancias-1.jpg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2025\\\/07\\\/infancias-1.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/ciudades-y-comunidades-prosperas\\\/ciudades-para-la-infancia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"name\":\"TecScience\",\"description\":\"Bilingual platform in charge of communicating advances in research, science and innovation at Tec\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\",\"name\":\"TecScience\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"width\":250,\"height\":38,\"caption\":\"TecScience\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TecScienceWeb\",\"https:\\\/\\\/x.com\\\/TecScience_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tec-science\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tecscienceweb\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/guia-de-publicacion-para-articulos-de-divulgacion\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/equipo-editorial-tecscience\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/a537c370cdc578d5d7ef285ecf5b1699\",\"name\":\"Nuria M\u00e1rquez Mart\u00ednez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09c34ee13e06f9bce21263e04c5e4b63d6a888c7c7045fb8f10db717b21b2279?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09c34ee13e06f9bce21263e04c5e4b63d6a888c7c7045fb8f10db717b21b2279?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/09c34ee13e06f9bce21263e04c5e4b63d6a888c7c7045fb8f10db717b21b2279?s=96&d=mm&r=g\",\"caption\":\"Nuria M\u00e1rquez Mart\u00ednez\"},\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/author\\\/nuriam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00bfC\u00f3mo pueden mejorar las ciudades pensando en la infancia? | TecScience","description":"\u00bfQu\u00e9 ven, sienten y necesitan ni\u00f1as y ni\u00f1os en sus ciudades? Urban95 Academy propone redise\u00f1ar el entorno a partir de sus experiencias.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfC\u00f3mo pueden mejorar las ciudades pensando en la infancia? | TecScience","og_description":"\u00bfQu\u00e9 ven, sienten y necesitan ni\u00f1as y ni\u00f1os en sus ciudades? Urban95 Academy propone redise\u00f1ar el entorno a partir de sus experiencias.","og_url":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/","og_site_name":"TecScience","article_publisher":"https:\/\/www.facebook.com\/TecScienceWeb","article_published_time":"2025-07-08T00:17:36+00:00","article_modified_time":"2025-10-07T21:56:09+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/infancias.jpg","type":"image\/jpeg"}],"author":"Nuria M\u00e1rquez Mart\u00ednez","twitter_card":"summary_large_image","twitter_title":"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina","twitter_creator":"@TecScience_","twitter_site":"@TecScience_","twitter_misc":{"Escrito por":"Nuria M\u00e1rquez Mart\u00ednez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#article","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/"},"author":{"name":"Nuria M\u00e1rquez Mart\u00ednez","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/a537c370cdc578d5d7ef285ecf5b1699"},"headline":"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina","datePublished":"2025-07-08T00:17:36+00:00","dateModified":"2025-10-07T21:56:09+00:00","mainEntityOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/"},"wordCount":1033,"publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/infancias-1.jpg","keywords":["Centro para el Futuro de las Ciudades"],"articleSection":["Ciudades y Comunidades Pr\u00f3speras"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/","url":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/","name":"\u00bfC\u00f3mo pueden mejorar las ciudades pensando en la infancia? | TecScience","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#primaryimage"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/infancias-1.jpg","datePublished":"2025-07-08T00:17:36+00:00","dateModified":"2025-10-07T21:56:09+00:00","description":"\u00bfQu\u00e9 ven, sienten y necesitan ni\u00f1as y ni\u00f1os en sus ciudades? Urban95 Academy propone redise\u00f1ar el entorno a partir de sus experiencias.","breadcrumb":{"@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#primaryimage","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/infancias-1.jpg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2025\/07\/infancias-1.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/tecscience.tec.mx\/es\/ciudades-y-comunidades-prosperas\/ciudades-para-la-infancia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecscience.tec.mx\/es\/"},{"@type":"ListItem","position":2,"name":"Invertir en la infancia transforma ciudades: Urban95 Academy llega a Am\u00e9rica Latina"}]},{"@type":"WebSite","@id":"https:\/\/tecscience.tec.mx\/es\/#website","url":"https:\/\/tecscience.tec.mx\/es\/","name":"TecScience","description":"Bilingual platform in charge of communicating advances in research, science and innovation at Tec","publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecscience.tec.mx\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tecscience.tec.mx\/es\/#organization","name":"TecScience","url":"https:\/\/tecscience.tec.mx\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","width":250,"height":38,"caption":"TecScience"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TecScienceWeb","https:\/\/x.com\/TecScience_","https:\/\/www.linkedin.com\/company\/tec-science\/","https:\/\/www.instagram.com\/tecscienceweb\/"],"publishingPrinciples":"https:\/\/tecscience.tec.mx\/es\/guia-de-publicacion-para-articulos-de-divulgacion\/","correctionsPolicy":"https:\/\/tecscience.tec.mx\/es\/equipo-editorial-tecscience\/"},{"@type":"Person","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/a537c370cdc578d5d7ef285ecf5b1699","name":"Nuria M\u00e1rquez Mart\u00ednez","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/09c34ee13e06f9bce21263e04c5e4b63d6a888c7c7045fb8f10db717b21b2279?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/09c34ee13e06f9bce21263e04c5e4b63d6a888c7c7045fb8f10db717b21b2279?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/09c34ee13e06f9bce21263e04c5e4b63d6a888c7c7045fb8f10db717b21b2279?s=96&d=mm&r=g","caption":"Nuria M\u00e1rquez Mart\u00ednez"},"url":"https:\/\/tecscience.tec.mx\/es\/author\/nuriam\/"}]}},"_links":{"self":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/178420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/comments?post=178420"}],"version-history":[{"count":0,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/178420\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media\/178470"}],"wp:attachment":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media?parent=178420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/categories?post=178420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/tags?post=178420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}