{"id":184423,"date":"2026-04-23T14:30:50","date_gmt":"2026-04-23T20:30:50","guid":{"rendered":"https:\/\/tecscience.tec.mx\/es\/?p=184423"},"modified":"2026-04-29T12:14:37","modified_gmt":"2026-04-29T18:14:37","slug":"transferencia-de-tecnologia-de-la-patente-al-mercado","status":"publish","type":"post","link":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/","title":{"rendered":"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Obtener una <a href=\"\/es\/negocios-innovacion\/propiedad-intelectual-investigadores\/\" target=\"_blank\" rel=\"noreferrer noopener\">patente<\/a> podr\u00eda parecer el \u00faltimo escal\u00f3n tras varios a\u00f1os de investigaci\u00f3n, pero en realidad es apenas el inicio del camino para generar impacto en el mundo real. Con ella comienza el proceso de transferencia de tecnolog\u00eda para convertir el conocimiento en aplicaciones concretas capaces de llegar al <a href=\"\/es\/negocios-innovacion\/transferencia-tecnologica\/\" target=\"_blank\" rel=\"noreferrer noopener\">mercado<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image alignright size-thumbnail\"><picture>\r\n                <source srcset=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/1516231957776-150x150.webp\" type=\"image\/webp\">\r\n                <img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/1516231957776-150x150.jpeg\" alt=\"\" class=\"wp-image-184456\" srcset=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/1516231957776-150x150.jpeg 150w, https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/1516231957776.jpeg 299w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\r\n            <\/picture><figcaption class=\"wp-element-caption\">Joel Cano, director de Transferencia de Tecnolog\u00eda en el Tec de Monterrey. Foto: Tec de Monterrey.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.linkedin.com\/in\/joelca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Joel Cano<\/a>, director de <a href=\"\/es\/tag\/transferencia-tecnologica\/\" target=\"_blank\" rel=\"noreferrer noopener\">Transferencia de Tecnolog\u00eda<\/a> en el Tecnol\u00f3gico de Monterrey, explica que, aunque la patente permite proteger el conocimiento que se genera en el laboratorio y otorga derechos sobre su uso, no define c\u00f3mo se va a utilizar ni en qu\u00e9 contextos tendr\u00e1 mayor valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa patente es apenas el primer paso de un viaje que hay que hacer desde un punto de vista cient\u00edfico y tecnol\u00f3gico\u201d, se\u00f1ala Cano. Una patente te da el derecho de <a href=\"\/es\/negocios-innovacion\/emprendimiento-de-base-cientifica-tecnologica\/\" target=\"_blank\" rel=\"noreferrer noopener\">utilizar esa tecnolog\u00eda<\/a>, pero todav\u00eda falta desarrollar cu\u00e1les son sus aplicaciones.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">De una invenci\u00f3n a m\u00faltiples aplicaciones<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando el Instituto Mexicano de la Propiedad Industrial (IMPI) otorga una patente, el siguiente paso para los investigadores es definir qu\u00e9 alcances tiene su innovaci\u00f3n y qu\u00e9 se puede hacer con ella. Una misma invenci\u00f3n puede tener m\u00faltiples aplicaciones para diferentes soluciones e industrias, dependiendo de c\u00f3mo se desarrolle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, menciona Cano, la <a href=\"https:\/\/conecta.tec.mx\/es\/noticias\/nacional\/emprendedores\/investigadores-tec-patentan-tecnologia-de-bioimpresion-de-tejidos\" target=\"_blank\" rel=\"noreferrer noopener\">patente<\/a> para un dispositivo de impresi\u00f3n ca\u00f3tica obtenida por investigadores del \u00c1lvarez-Trujillo Lab es aprovechada por <a href=\"\/es\/biotecnologia\/carne-impresion-3d\/\" target=\"_blank\" rel=\"noreferrer noopener\">Forma Foods<\/a>, una <a href=\"\/es\/negocios-innovacion\/nuevas-empresas-de-base-cientifico-tecnologica\/\" target=\"_blank\" rel=\"noreferrer noopener\">empresa de base cient\u00edfico-tecnol\u00f3gica<\/a> del Tec enfocada en innovar en la industria de alimentos. Pero tambi\u00e9n tiene potencial para impactar en el sector salud, con la capacidad para imprimir tumores que permitan probar tratamientos en el laboratorio y no en los pacientes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAs\u00ed como podemos imprimir carne a partir de prote\u00ednas vegetales para alimentarnos, tambi\u00e9n podemos imprimir tumores para probar medicamentos; es la misma tecnolog\u00eda con aplicaciones completamente distintas\u201d, comenta Cano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agrega que, en ese sentido, los investigadores deben preguntarse y explorar cu\u00e1les son las aplicaciones que pueden tener mayor valor o deseabilidad en un mercado espec\u00edfico. Incluso despu\u00e9s de este an\u00e1lisis, una patente puede convertirse en una plataforma tecnol\u00f3gica para el nacimiento de otras innovaciones que tambi\u00e9n pueden patentarse.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\u00bfComer\u00edas una carne producida en un laboratorio? Estos son los alimentos del futuro\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/h9G4wBYBtTU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Validaci\u00f3n de mercado e impacto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El director se\u00f1ala que, cuando ya se han identificado posibles aplicaciones, es necesario buscar clientes potenciales con los que se pueda trabajar. Por ejemplo, en modelos de negocio entre empresas (B2B) o dirigidos a consumidores finales (B2C), para entender si la tecnolog\u00eda de esta patente responde a una necesidad concreta en el mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTienes que salirte del laboratorio ya con tu patente a la mano, ya protegida, y empezar a generar alianzas o negocios con clientes potenciales; por ejemplo, en un modelo de negocio a negocio, identificar qu\u00e9 empresas podr\u00edan utilizar esa tecnolog\u00eda en particular y, a partir de ah\u00ed, desarrollar alianzas y llevar a cabo la validaci\u00f3n\u201d, dice Cano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este <strong>proceso para validar una tecnolog\u00eda<\/strong>, se utilizan m\u00faltiples criterios que ayudan a medir su potencial. Por ejemplo, en el Tec de Monterrey se aplican dos tipos de m\u00e9tricas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>De mercado:<\/strong> para saber si tiene demanda, atiende una necesidad real y tiene viabilidad comercial.<\/li>\n\n\n\n<li><strong>De impacto:<\/strong> para identificar si resuelve un problema relevante (salud, medio ambiente o manufactura) y genera beneficios m\u00e1s all\u00e1 del mercado.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn el Tec tenemos una clasificaci\u00f3n de cu\u00e1les se han identificado a trav\u00e9s de un mecanismo comercial o econ\u00f3mico y a trav\u00e9s de uno de impacto, y se organizan justo por esas necesidades del mercado\u201d, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPuede ser la necesidad de una industria o una empresa en particular, pero tambi\u00e9n puede ser un impacto en un sector espec\u00edfico del pa\u00eds. Por ejemplo, en el \u00e1rea de salud, los temas de obesidad que identificamos a trav\u00e9s de un instituto que justamente analiza los impactos que genera este problema. Ah\u00ed decimos: \u2018Oye, esto tiene un valor comercial, pero tambi\u00e9n social o de salud importante\u2019 y lo clasificamos en funci\u00f3n de eso\u201d.\u00a0<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prototipos y productos m\u00ednimos viables<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el proceso de validaci\u00f3n, el siguiente paso es desarrollar versiones de la tecnolog\u00eda que se puedan probar en condiciones cercanas a la realidad, es decir, crear prototipos o productos m\u00ednimos viables (MVP, por sus siglas en ingl\u00e9s) que se puedan validar a trav\u00e9s de modelos \u00e1giles, que son metodolog\u00edas para hacer evaluaciones y ajustes r\u00e1pidos y con pocos recursos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se consideran <strong>dos dimensiones para identificar la evoluci\u00f3n de la tecnolog\u00eda<\/strong> y saber qu\u00e9 tan cerca est\u00e1 de llegar al mercado:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Technology Readiness Level <strong>(TRL<\/strong><\/strong>)<strong>:<\/strong> Mide su madurez t\u00e9cnica, desde pruebas iniciales en laboratorio hasta una aplicaci\u00f3n lista para usarse en condiciones reales.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Innovation Readiness Level (IRL):<\/strong> Eval\u00faa qu\u00e9 tan preparado est\u00e1 el entorno para adoptar la innovaci\u00f3n, considerando factores como regulaci\u00f3n, demanda y viabilidad de implementaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Licenciamiento o <em>spin-off<\/em>: dos rutas para llegar al mercado<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando la tecnolog\u00eda ya tiene un avance significativo, se deben tomar decisiones sobre su camino hacia el mercado; por ejemplo, decidir si se licenciar\u00e1 la tecnolog\u00eda a una empresa que ya existe o se crear\u00e1 un nuevo emprendimiento, como una <em>spin-off<\/em>, es decir, una empresa derivada de la investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cano dice que esta es una decisi\u00f3n de negocios y depende de diversos factores, como el tama\u00f1o del mercado, el <a href=\"\/es\/transformacion-industrial\/emprendimiento-cientifico-mexico-valle-muerte\/\" target=\"_blank\" rel=\"noreferrer noopener\">riesgo<\/a> y la necesidad de capital para escalar la innovaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAh\u00ed es donde t\u00fa tienes que empezar a decir: \u2018Ok, yo genero a lo mejor la idea original en un grupo de investigadores y luego se conecta con emprendedores que pueden levantar alg\u00fan tipo de capital y llevar a la siguiente fase\u2019. Pero tal vez en la \u00faltima etapa requieres inversiones de una industria, como la farmac\u00e9utica, y este proyecto que ya se convirti\u00f3 en un emprendimiento requiere una inversi\u00f3n millonaria para escalar esa tecnolog\u00eda a nivel global y hay que buscar un comprador\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escalar requiere inversi\u00f3n y aliados<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eso no significar\u00eda haber hecho un mal negocio, se\u00f1ala Cano; por el contrario, ser\u00eda haber identificado el nivel de escala de inversi\u00f3n y de oportunidad, que debe crecer de manera geom\u00e9trica y no lineal, pues las inversiones que requiere la tecnolog\u00eda para ir avanzando cada etapa atraviesan desde un nivel de <em>startup<\/em> hasta una escala global con la transferencia de tecnolog\u00eda a una empresa multinacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este camino, los investigadores deben atravesar distintas etapas de inversi\u00f3n, que van desde el capital inicial y semilla, donde las instituciones acad\u00e9micas como el Tec pueden participar, hasta rondas avanzadas, como las series A, B o C, que suelen involucrar fondos de capital de riesgo (<em>venture capital<\/em>) y empresas que buscan adquirir tecnolog\u00edas maduras y con gran potencial para el mercado.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"\u00bfQu\u00e9 es la transferencia tecnol\u00f3gica?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/F3htAPeO6Mw?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">El ecosistema del Tec para transferencia tecnol\u00f3gica<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En el Tec, los investigadores son acompa\u00f1ados durante toda la ruta de su proyecto de innovaci\u00f3n a trav\u00e9s de la infraestructura y las <a href=\"\/es\/tecnologia\/plataformas-del-tec-de-monterrey-para-investigadores\/\" target=\"_blank\" rel=\"noreferrer noopener\">herramientas<\/a> que ofrecen los Distritos de Innovaci\u00f3n, la Direcci\u00f3n de Transferencia de Tecnolog\u00eda y el Instituto de Emprendimiento Eugenio Garza Lag\u00fcera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cano se\u00f1ala que la duraci\u00f3n de una patente depende de la tecnolog\u00eda y el tipo de protecci\u00f3n, pero puede alcanzar los 20 o 30 a\u00f1os. En esta ruta, los investigadores pueden obtener beneficios econ\u00f3micos como inventores, pero tambi\u00e9n como emprendedores al asumir un rol en la <em>startup<\/em>. Adem\u00e1s, considera que es un trabajo que no termina, pues ve necesaria una inversi\u00f3n continua en investigaci\u00f3n y desarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs un camino que termina siendo como una especie de Lego; la primera patente es la base de una figura, pero vas generando componentes adicionales que pueden ser futuros activos de una nueva empresa creada, que a su vez puede invertir en investigaci\u00f3n y desarrollo para crear tecnolog\u00eda nueva y adicional que no tiene que ver con la patente original\u201d, se\u00f1ala.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para el director, <strong>el \u00e9xito de una patente va m\u00e1s all\u00e1 de proteger una tecnolog\u00eda: est\u00e1 en su capacidad para resolver problemas reales. <\/strong>La clave est\u00e1 en que, como innovaci\u00f3n, pueda encontrar su vocaci\u00f3n de mercado o de impacto que le permita tener una estrategia de crecimiento basada en resolver necesidades y en la integraci\u00f3n con otras disciplinas y nuevas tecnolog\u00edas, como la inteligencia artificial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>\u00bfTe interes\u00f3 esta historia? \u00bfQuieres publicarla? Contacta a nuestra editora de contenido para m\u00e1s informaci\u00f3n:&nbsp;<a href=\"mailto:marianaleonm@tec.mx\">marianaleonm@tec.mx<\/a><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Tec acompa\u00f1a a sus investigadores en la validaci\u00f3n comercial de sus patentes, el desarrollo de prototipos y el escalamiento de tecnolog\u00edas mediante licenciamiento o spin-offs.<\/p>\n","protected":false},"author":47,"featured_media":184430,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_eb_attr":"","footnotes":""},"categories":[100],"tags":[164],"class_list":["post-184423","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios-innovacion","tag-transferencia-tecnologica"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.0 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Despu\u00e9s de la patente: \u00bfqu\u00e9 sigue para llegar al mercado? | TecScience<\/title>\n<meta name=\"description\" content=\"Tras obtener una patente, el reto es convertirla en innovaci\u00f3n aplicada. Conoce la ruta para validar una tecnolog\u00eda, desarrollar prototipos y escalarla en el Tec de Monterrey.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado\" \/>\n<meta property=\"og:description\" content=\"Tras obtener una patente, el reto es convertirla en innovaci\u00f3n aplicada. Conoce la ruta para validar una tecnolog\u00eda, desarrollar prototipos y escalarla en el Tec de Monterrey.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/\" \/>\n<meta property=\"og:site_name\" content=\"TecScience\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TecScienceWeb\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-23T20:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T18:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/despues-de-la-patente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Trevi\u00f1o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:site\" content=\"@TecScience_\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Trevi\u00f1o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/\"},\"author\":{\"name\":\"Ricardo Trevi\u00f1o\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/d0ed5b5fa0ab2c4754211e4addf201dc\"},\"headline\":\"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado\",\"datePublished\":\"2026-04-23T20:30:50+00:00\",\"dateModified\":\"2026-04-29T18:14:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/\"},\"wordCount\":1499,\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/despues-de-la-patente.jpg\",\"keywords\":[\"Transferencia Tecnol\u00f3gica\"],\"articleSection\":[\"Negocios e Innovaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/\",\"name\":\"Despu\u00e9s de la patente: \u00bfqu\u00e9 sigue para llegar al mercado? | TecScience\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/despues-de-la-patente.jpg\",\"datePublished\":\"2026-04-23T20:30:50+00:00\",\"dateModified\":\"2026-04-29T18:14:37+00:00\",\"description\":\"Tras obtener una patente, el reto es convertirla en innovaci\u00f3n aplicada. Conoce la ruta para validar una tecnolog\u00eda, desarrollar prototipos y escalarla en el Tec de Monterrey.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/despues-de-la-patente.jpg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2026\\\/04\\\/despues-de-la-patente.jpg\",\"width\":750,\"height\":500,\"caption\":\"Despu\u00e9s de obtener una patente, los investigadores deben seguir una ruta para transformar el conocimiento en aplicaciones capaces de llegar al mercado. (Ilustraci\u00f3n: Getty Images)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/negocios-innovacion\\\/transferencia-de-tecnologia-de-la-patente-al-mercado\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"name\":\"TecScience\",\"description\":\"Bilingual platform in charge of communicating advances in research, science and innovation at Tec\",\"publisher\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#organization\",\"name\":\"TecScience\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"contentUrl\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2022\\\/11\\\/logo-negro-tecscience.svg\",\"width\":250,\"height\":38,\"caption\":\"TecScience\"},\"image\":{\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TecScienceWeb\",\"https:\\\/\\\/x.com\\\/TecScience_\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tec-science\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tecscienceweb\\\/\"],\"publishingPrinciples\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/guia-de-publicacion-para-articulos-de-divulgacion\\\/\",\"correctionsPolicy\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/equipo-editorial-tecscience\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/#\\\/schema\\\/person\\\/d0ed5b5fa0ab2c4754211e4addf201dc\",\"name\":\"Ricardo Trevi\u00f1o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bcc2569d80f3bc04d35c88e014da852d10420f44fbbf0158af3ce158042ba08?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bcc2569d80f3bc04d35c88e014da852d10420f44fbbf0158af3ce158042ba08?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4bcc2569d80f3bc04d35c88e014da852d10420f44fbbf0158af3ce158042ba08?s=96&d=mm&r=g\",\"caption\":\"Ricardo Trevi\u00f1o\"},\"url\":\"https:\\\/\\\/tecscience.tec.mx\\\/es\\\/author\\\/rtrevino\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Despu\u00e9s de la patente: \u00bfqu\u00e9 sigue para llegar al mercado? | TecScience","description":"Tras obtener una patente, el reto es convertirla en innovaci\u00f3n aplicada. Conoce la ruta para validar una tecnolog\u00eda, desarrollar prototipos y escalarla en el Tec de Monterrey.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/","og_locale":"es_ES","og_type":"article","og_title":"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado","og_description":"Tras obtener una patente, el reto es convertirla en innovaci\u00f3n aplicada. Conoce la ruta para validar una tecnolog\u00eda, desarrollar prototipos y escalarla en el Tec de Monterrey.","og_url":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/","og_site_name":"TecScience","article_publisher":"https:\/\/www.facebook.com\/TecScienceWeb","article_published_time":"2026-04-23T20:30:50+00:00","article_modified_time":"2026-04-29T18:14:37+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/despues-de-la-patente.jpg","type":"image\/jpeg"}],"author":"Ricardo Trevi\u00f1o","twitter_card":"summary_large_image","twitter_creator":"@TecScience_","twitter_site":"@TecScience_","twitter_misc":{"Escrito por":"Ricardo Trevi\u00f1o","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#article","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/"},"author":{"name":"Ricardo Trevi\u00f1o","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/d0ed5b5fa0ab2c4754211e4addf201dc"},"headline":"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado","datePublished":"2026-04-23T20:30:50+00:00","dateModified":"2026-04-29T18:14:37+00:00","mainEntityOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/"},"wordCount":1499,"publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/despues-de-la-patente.jpg","keywords":["Transferencia Tecnol\u00f3gica"],"articleSection":["Negocios e Innovaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/","url":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/","name":"Despu\u00e9s de la patente: \u00bfqu\u00e9 sigue para llegar al mercado? | TecScience","isPartOf":{"@id":"https:\/\/tecscience.tec.mx\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#primaryimage"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#primaryimage"},"thumbnailUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/despues-de-la-patente.jpg","datePublished":"2026-04-23T20:30:50+00:00","dateModified":"2026-04-29T18:14:37+00:00","description":"Tras obtener una patente, el reto es convertirla en innovaci\u00f3n aplicada. Conoce la ruta para validar una tecnolog\u00eda, desarrollar prototipos y escalarla en el Tec de Monterrey.","breadcrumb":{"@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#primaryimage","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/despues-de-la-patente.jpg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2026\/04\/despues-de-la-patente.jpg","width":750,"height":500,"caption":"Despu\u00e9s de obtener una patente, los investigadores deben seguir una ruta para transformar el conocimiento en aplicaciones capaces de llegar al mercado. (Ilustraci\u00f3n: Getty Images)"},{"@type":"BreadcrumbList","@id":"https:\/\/tecscience.tec.mx\/es\/negocios-innovacion\/transferencia-de-tecnologia-de-la-patente-al-mercado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tecscience.tec.mx\/es\/"},{"@type":"ListItem","position":2,"name":"Despu\u00e9s de la patente: c\u00f3mo llevar la ciencia del laboratorio al mercado"}]},{"@type":"WebSite","@id":"https:\/\/tecscience.tec.mx\/es\/#website","url":"https:\/\/tecscience.tec.mx\/es\/","name":"TecScience","description":"Bilingual platform in charge of communicating advances in research, science and innovation at Tec","publisher":{"@id":"https:\/\/tecscience.tec.mx\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tecscience.tec.mx\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/tecscience.tec.mx\/es\/#organization","name":"TecScience","url":"https:\/\/tecscience.tec.mx\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/","url":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","contentUrl":"https:\/\/tecscience.tec.mx\/es\/wp-content\/uploads\/sites\/8\/2022\/11\/logo-negro-tecscience.svg","width":250,"height":38,"caption":"TecScience"},"image":{"@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TecScienceWeb","https:\/\/x.com\/TecScience_","https:\/\/www.linkedin.com\/company\/tec-science\/","https:\/\/www.instagram.com\/tecscienceweb\/"],"publishingPrinciples":"https:\/\/tecscience.tec.mx\/es\/guia-de-publicacion-para-articulos-de-divulgacion\/","correctionsPolicy":"https:\/\/tecscience.tec.mx\/es\/equipo-editorial-tecscience\/"},{"@type":"Person","@id":"https:\/\/tecscience.tec.mx\/es\/#\/schema\/person\/d0ed5b5fa0ab2c4754211e4addf201dc","name":"Ricardo Trevi\u00f1o","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4bcc2569d80f3bc04d35c88e014da852d10420f44fbbf0158af3ce158042ba08?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4bcc2569d80f3bc04d35c88e014da852d10420f44fbbf0158af3ce158042ba08?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4bcc2569d80f3bc04d35c88e014da852d10420f44fbbf0158af3ce158042ba08?s=96&d=mm&r=g","caption":"Ricardo Trevi\u00f1o"},"url":"https:\/\/tecscience.tec.mx\/es\/author\/rtrevino\/"}]}},"_links":{"self":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/184423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/comments?post=184423"}],"version-history":[{"count":0,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/posts\/184423\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media\/184430"}],"wp:attachment":[{"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/media?parent=184423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/categories?post=184423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecscience.tec.mx\/es\/wp-json\/wp\/v2\/tags?post=184423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}